{"id":517,"date":"2024-06-13T11:28:23","date_gmt":"2024-06-13T11:28:23","guid":{"rendered":"https:\/\/www.cafeteriapuntoycoma.com\/?page_id=517"},"modified":"2024-06-13T11:54:02","modified_gmt":"2024-06-13T11:54:02","slug":"politica-de-cookies","status":"publish","type":"page","link":"https:\/\/www.cafeteriapuntoycoma.com\/en\/politica-de-cookies\/","title":{"rendered":"Pol\u00edtica de Cookies"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"517\" class=\"elementor elementor-517\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c4ac5f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c4ac5f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-86f5a66 elementor-invisible\" data-id=\"86f5a66\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b98ec24 elementor-widget elementor-widget-image\" data-id=\"b98ec24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.cafeteriapuntoycoma.com\/en\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"700\" height=\"700\" src=\"https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/Logo-pyc-02.png\" class=\"elementor-animation-float attachment-large size-large wp-image-228\" alt=\"\" srcset=\"https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/Logo-pyc-02.png 700w, https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/Logo-pyc-02-300x300.png 300w, https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/Logo-pyc-02-150x150.png 150w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ed07d9a\" data-id=\"ed07d9a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f249634 elementor-section-full_width elementor-reverse-tablet elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"f249634\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a6b6f57 elementor-invisible\" data-id=\"a6b6f57\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f75aa1 elementor-widget elementor-widget-jkit_nav_menu\" data-id=\"5f75aa1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;st_submenu_item_text_normal_bg_background_background&quot;:&quot;classic&quot;}\" data-widget_type=\"jkit_nav_menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-nav-menu break-point-tablet submenu-click-title jeg_module___6a979f6f7808a\"  data-item-indicator=\"&lt;svg aria-hidden=&quot;true&quot; class=&quot;e-font-icon-svg e-fas-angle-down&quot; viewBox=&quot;0 0 320 512&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot;&gt;&lt;path d=&quot;M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z&quot;&gt;&lt;\/path&gt;&lt;\/svg&gt;\"><button aria-label=\"open-menu\" class=\"jkit-hamburger-menu\"><i aria-hidden=\"true\" class=\"jki jki-burger-menu-light\"><\/i><\/button>\n        <div class=\"jkit-menu-wrapper\"><div class=\"jkit-menu-container\"><ul id=\"menu-menu-pyc\" class=\"jkit-menu jkit-menu-direction-flex jkit-submenu-position-top\"><li id=\"menu-item-141\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-141\"><a href=\"https:\/\/www.cafeteriapuntoycoma.com\/en\/\">HOME<\/a><\/li>\n<li id=\"menu-item-142\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-142\"><a href=\"https:\/\/www.cafeteriapuntoycoma.com\/en\/nosotros\/\">ABOUT US<\/a><\/li>\n<li id=\"menu-item-143\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-143\"><a href=\"https:\/\/www.cafeteriapuntoycoma.com\/en\/menu\/\">MENU<\/a><\/li>\n<li id=\"menu-item-144\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-144\"><a href=\"https:\/\/www.cafeteriapuntoycoma.com\/en\/contacto\/\">CONTACT<\/a><\/li>\n<li id=\"menu-item-480\" class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-480\"><a href=\"https:\/\/www.cafeteriapuntoycoma.com\/en\/wp-json\/wp\/v2\/pages\/517\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/es_ES.png\" width=\"18\" height=\"12\" alt=\"es_ES\" title=\"Spanish\"><\/span><\/a><\/li>\n<li id=\"menu-item-479\" class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-479\"><a href=\"https:\/\/www.cafeteriapuntoycoma.com\/en\/wp-json\/wp\/v2\/pages\/517\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/en_GB.png\" width=\"18\" height=\"12\" alt=\"en_GB\" title=\"English\"><\/span><\/a><\/li>\n<\/ul><\/div>\n            <div class=\"jkit-nav-identity-panel\">\n                <div class=\"jkit-nav-site-title\"><a href=\"https:\/\/www.cafeteriapuntoycoma.com\/en\" class=\"jkit-nav-logo\" aria-label=\"Home Link\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/cropped-Logo-pyc-02.png\" class=\"attachment-2048x2048 size-2048x2048\" alt=\"\" srcset=\"https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/cropped-Logo-pyc-02.png 512w, https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/cropped-Logo-pyc-02-300x300.png 300w, https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/cropped-Logo-pyc-02-150x150.png 150w, https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/cropped-Logo-pyc-02-270x270.png 270w, https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/cropped-Logo-pyc-02-192x192.png 192w, https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/cropped-Logo-pyc-02-180x180.png 180w, https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/cropped-Logo-pyc-02-32x32.png 32w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/a><\/div>\n                <button aria-label=\"close-menu\" class=\"jkit-close-menu\"><i aria-hidden=\"true\" class=\"jki jki-times-solid\"><\/i><\/button>\n            <\/div>\n        <\/div>\n        <div class=\"jkit-overlay\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fbcca40 elementor-invisible\" data-id=\"fbcca40\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0245854 elementor-hidden-phone elementor-tablet-align-right elementor-widget elementor-widget-button\" data-id=\"0245854\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"tel:+34986958006\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CALL US<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6563b45d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6563b45d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42ad6e5d\" data-id=\"42ad6e5d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53fc01a0 elementor-widget elementor-widget-heading\" data-id=\"53fc01a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pol\u00edtica de Cookies<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d0c9b21 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d0c9b21\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dae4e9f\" data-id=\"dae4e9f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75f89c7 elementor-widget elementor-widget-text-editor\" data-id=\"75f89c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"row\"><div class=\"col-xl-10 mx-auto\"><div class=\"paper\"><header class=\"text-center\"><div class=\"row\"><div class=\"col-xl-10 mx-auto\"><div class=\"paper\"><header class=\"text-center\"><h2 class=\"m-auto\">POL\u00cdTICA DE COOKIES<\/h2><p>\u00a0<\/p><h4><span class=\"blanc-space ng-binding\">https:\/\/www.cafeteriapuntoycoma.com<\/span><\/h4><\/header><div><p>El acceso a este Sitio Web puede implicar la utilizaci\u00f3n de cookies. Las cookies son peque\u00f1as cantidades de informaci\u00f3n que se almacenan en el navegador utilizado por cada Usuario \u2014en los distintos dispositivos que pueda utilizar para navegar\u2014 para que el servidor recuerde cierta informaci\u00f3n que posteriormente y \u00fanicamente el servidor que la implement\u00f3 leer\u00e1. Las cookies facilitan la navegaci\u00f3n, la hacen m\u00e1s amigable, y no da\u00f1an el dispositivo de navegaci\u00f3n.<\/p><p>Las cookies son procedimientos autom\u00e1ticos de recogida de informaci\u00f3n relativa a las preferencias determinadas por el Usuario durante su visita al Sitio Web con el fin de reconocerlo como Usuario, y personalizar su experiencia y el uso del Sitio Web, y pueden tambi\u00e9n, por ejemplo, ayudar a identificar y resolver errores.<\/p><p>La informaci\u00f3n recabada a trav\u00e9s de las cookies puede incluir la fecha y hora de visitas al Sitio Web, las p\u00e1ginas visionadas, el tiempo que ha estado en el Sitio Web y los sitios visitados justo antes y despu\u00e9s del mismo. Sin embargo, ninguna cookie permite que esta misma pueda contactarse con el n\u00famero de tel\u00e9fono del Usuario o con cualquier otro medio de contacto personal. Ninguna cookie puede extraer informaci\u00f3n del disco duro del Usuario o robar informaci\u00f3n personal. La \u00fanica manera de que la informaci\u00f3n privada del Usuario forme parte del archivo Cookie es que el usuario d\u00e9 personalmente esa informaci\u00f3n al servidor.<\/p><p>Las cookies que permiten identificar a una persona se consideran datos personales. Por tanto, a las mismas les ser\u00e1 de aplicaci\u00f3n la Pol\u00edtica de Privacidad anteriormente descrita. En este sentido, para la utilizaci\u00f3n de las mismas ser\u00e1 necesario el consentimiento del Usuario. Este consentimiento ser\u00e1 comunicado, en base a una elecci\u00f3n aut\u00e9ntica, ofrecido mediante una decisi\u00f3n afirmativa y positiva, antes del tratamiento inicial, removible y documentado.<\/p><div class=\"\"><h4>Cookies propias<\/h4><p>Son aquellas cookies que son enviadas al ordenador o dispositivo del Usuario y gestionadas exclusivamente por <span class=\"blanc-space ng-binding\">Cafeter\u00eda Punto &amp; Coma<\/span> para el mejor funcionamiento del Sitio Web. La informaci\u00f3n que se recaba se emplea para mejorar la calidad del Sitio Web y su Contenido y su experiencia como Usuario. Estas cookies permiten reconocer al Usuario como visitante recurrente del Sitio Web y adaptar el contenido para ofrecerle contenidos que se ajusten a sus preferencias.<\/p><\/div><div class=\"thirdCookies\"><h4>Cookies de terceros<\/h4><p>Son cookies utilizadas y gestionadas por entidades externas que proporcionan a <span class=\"blanc-space ng-binding\">Cafeter\u00eda Punto &amp; Coma<\/span> servicios solicitados por este mismo para mejorar el Sitio Web y la experiencia del usuario al navegar en el Sitio Web. Los principales objetivos para los que se utilizan cookies de terceros son la obtenci\u00f3n de estad\u00edsticas de accesos y analizar la informaci\u00f3n de la navegaci\u00f3n, es decir, c\u00f3mo interact\u00faa el Usuario con el Sitio Web.<\/p><p>La informaci\u00f3n que se obtiene se refiere, por ejemplo, al n\u00famero de p\u00e1ginas visitadas, el idioma, el lugar a la que la direcci\u00f3n IP desde el que accede el Usuario, el n\u00famero de Usuarios que acceden, la frecuencia y reincidencia de las visitas, el tiempo de visita, el navegador que usan, el operador o tipo de dispositivo desde el que se realiza la visita. Esta informaci\u00f3n se utiliza para mejorar el Sitio Web, y detectar nuevas necesidades para ofrecer a los Usuarios un Contenido y\/o servicio de \u00f3ptima calidad. En todo caso, la informaci\u00f3n se recopila de forma an\u00f3nima y se elaboran informes de tendencias del Sitio Web sin identificar a usuarios individuales.<\/p><p>Puede obtener m\u00e1s informaci\u00f3n sobre las cookies, la informaci\u00f3n sobre la privacidad, o consultar la descripci\u00f3n del tipo de cookies que se utiliza, sus principales caracter\u00edsticas, periodo de expiraci\u00f3n, etc. en el siguiente(s) enlace(s):<\/p><p class=\"text-wrap ng-binding\">Google Analytics<\/p><p>La(s) entidad(es) encargada(s) del suministro de cookies podr\u00e1(n) ceder esta informaci\u00f3n a terceros, siempre y cuando lo exija la ley o sea un tercero el que procese esta informaci\u00f3n para dichas entidades.<\/p><\/div><div class=\"\"><h4>Cookies de redes sociales<\/h4><p><span class=\"blanc-space ng-binding\">Cafeter\u00eda Punto &amp; Coma<\/span> incorpora plugins de redes sociales, que permiten acceder a las mismas a partir del Sitio Web. Por esta raz\u00f3n, las cookies de redes sociales pueden almacenarse en el navegador del Usuario. Los titulares de dichas redes sociales disponen de sus propias pol\u00edticas de protecci\u00f3n de datos y de cookies, siendo ellos mismos, en cada caso, responsables de sus propios ficheros y de sus propias pr\u00e1cticas de privacidad. El Usuario debe referirse a las mismas para informarse acerca de dichas cookies y, en su caso, del tratamiento de sus datos personales. \u00danicamente a t\u00edtulo informativo se indican a continuaci\u00f3n los enlaces en los que se pueden consultar dichas pol\u00edticas de privacidad y\/o de cookies:<\/p><ul><li>Facebook: <a class=\"text-info\" href=\"https:\/\/www.facebook.com\/policies\/cookies\/\">https:\/\/www.facebook.com\/policies\/cookies\/<\/a><\/li><li>Twitter: <a class=\"text-info\" href=\"https:\/\/twitter.com\/es\/privacy\">https:\/\/twitter.com\/es\/privacy<\/a><\/li><li>Instagram: <a class=\"text-info\" href=\"https:\/\/help.instagram.com\/1896641480634370?ref=ig\">https:\/\/help.instagram.com\/1896641480634370?ref=ig<\/a><\/li><li>YouTube: <a class=\"text-info\" href=\"https:\/\/policies.google.com\/privacy?hl=es-419&amp;gl=mx\">https:\/\/policies.google.com\/privacy?hl=es-419&amp;gl=mx<\/a><\/li><li>Pinterest: <a class=\"text-info\" href=\"https:\/\/policy.pinterest.com\/es\/privacy-policy\">https:\/\/policy.pinterest.com\/es\/privacy-policy<\/a><\/li><li>LinkedIn: <a class=\"text-info\" href=\"https:\/\/www.linkedin.com\/legal\/cookie-policy?trk=hp-cookies\">https:\/\/www.linkedin.com\/legal\/cookie-policy?trk=hp-cookies<\/a><\/li><\/ul><\/div><h4>Deshabilitar, rechazar y eliminar cookies<\/h4><p>El Usuario puede deshabilitar, rechazar y eliminar las cookies \u2014total o parcialmente\u2014 instaladas en su dispositivo mediante la configuraci\u00f3n de su navegador (entre los que se encuentran, por ejemplo, Chrome, Firefox, Safari, Explorer). En este sentido, los procedimientos para rechazar y eliminar las cookies pueden diferir de un navegador de Internet a otro. En consecuencia, el Usuario debe acudir a las instrucciones facilitadas por el propio navegador de Internet que est\u00e9 utilizando. En el supuesto de que rechace el uso de cookies \u2014total o parcialmente\u2014 podr\u00e1 seguir usando el Sitio Web, si bien podr\u00e1 tener limitada la utilizaci\u00f3n de algunas de las prestaciones del mismo.<\/p><\/div><\/div><\/div><\/div><\/header><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d02feef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d02feef\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-ec653c0 elementor-invisible\" data-id=\"ec653c0\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9120115 elementor-widget elementor-widget-image\" data-id=\"9120115\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"183\" src=\"https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/Logo-pycfull-01.png\" class=\"attachment-large size-large wp-image-309\" alt=\"\" srcset=\"https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/Logo-pycfull-01.png 934w, https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/Logo-pycfull-01-300x69.png 300w, https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/Logo-pycfull-01-768x176.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6e2df3 elementor-widget elementor-widget-text-editor\" data-id=\"e6e2df3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Your caf\u00e9-bar in Navia, Vigo. Large terrace, delicious variety of food, ideal for group dinners and families with an adjoining children's playground. Come and enjoy!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-5cfc925 elementor-invisible\" data-id=\"5cfc925\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-059d377 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"059d377\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Location<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b4e09a elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8b4e09a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/maps.app.goo.gl\/LjyStkckNoaskAuq6\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Rua Teixugueiras, 18, 36212 Vigo, Pontevedra<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-470f3b9 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"470f3b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+34986958006\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">986 95 80 06<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b870b0e elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b870b0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:puntoycomaenvigo@gmail.com\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-envelope\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M502.3 190.8c3.9-3.1 9.7-.2 9.7 4.7V400c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V195.6c0-5 5.7-7.8 9.7-4.7 22.4 17.4 52.1 39.5 154.1 113.6 21.1 15.4 56.7 47.8 92.2 47.6 35.7.3 72-32.8 92.3-47.6 102-74.1 131.6-96.3 154-113.7zM256 320c23.2.4 56.6-29.2 73.4-41.4 132.7-96.3 142.8-104.7 173.4-128.7 5.8-4.5 9.2-11.5 9.2-18.9v-19c0-26.5-21.5-48-48-48H48C21.5 64 0 85.5 0 112v19c0 7.4 3.4 14.3 9.2 18.9 30.6 23.9 40.7 32.4 173.4 128.7 16.8 12.2 50.2 41.8 73.4 41.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">puntoycomaenvigo@gmail.com<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-b5f47e9 elementor-invisible\" data-id=\"b5f47e9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:400}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8b1cd4 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a8b1cd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Links<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-404adeb hfe-nav-menu__breakpoint-none hfe-nav-menu__align-left hfe-submenu-icon-arrow hfe-link-redirect-child elementor-widget elementor-widget-navigation-menu\" data-id=\"404adeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;padding_vertical_menu_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:6,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:12,&quot;sizes&quot;:[]},&quot;padding_horizontal_menu_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;padding_horizontal_menu_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_menu_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;dropdown_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;padding_horizontal_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"navigation-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"hfe-nav-menu hfe-layout-vertical hfe-nav-menu-layout vertical\" data-layout=\"vertical\">\n\t\t\t\t<div role=\"button\" class=\"hfe-nav-menu__toggle elementor-clickable\" tabindex=\"0\" aria-label=\"Menu Toggle\">\n\t\t\t\t\t<span class=\"screen-reader-text\">Menu<\/span>\n\t\t\t\t\t<div class=\"hfe-nav-menu-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<nav class=\"hfe-nav-menu__layout-vertical hfe-nav-menu__submenu-arrow\" data-toggle-icon=\"\" data-close-icon=\"\" data-full-width=\"\">\n\t\t\t\t\t<ul id=\"menu-1-404adeb\" class=\"hfe-nav-menu\"><li id=\"menu-item-141\" class=\"menu-item menu-item-type-custom menu-item-object-custom parent hfe-creative-menu\"><a href=\"https:\/\/www.cafeteriapuntoycoma.com\/en\/\" class = \"hfe-menu-item\">HOME<\/a><\/li>\n<li id=\"menu-item-142\" class=\"menu-item menu-item-type-custom menu-item-object-custom parent hfe-creative-menu\"><a href=\"https:\/\/www.cafeteriapuntoycoma.com\/en\/nosotros\/\" class = \"hfe-menu-item\">ABOUT US<\/a><\/li>\n<li id=\"menu-item-143\" class=\"menu-item menu-item-type-custom menu-item-object-custom parent hfe-creative-menu\"><a href=\"https:\/\/www.cafeteriapuntoycoma.com\/en\/menu\/\" class = \"hfe-menu-item\">MENU<\/a><\/li>\n<li id=\"menu-item-144\" class=\"menu-item menu-item-type-custom menu-item-object-custom parent hfe-creative-menu\"><a href=\"https:\/\/www.cafeteriapuntoycoma.com\/en\/contacto\/\" class = \"hfe-menu-item\">CONTACT<\/a><\/li>\n<li id=\"menu-item-480\" class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item parent hfe-creative-menu\"><a href=\"https:\/\/www.cafeteriapuntoycoma.com\/en\/wp-json\/wp\/v2\/pages\/517\" class = \"hfe-menu-item\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/es_ES.png\" width=\"18\" height=\"12\" alt=\"es_ES\" title=\"Spanish\"><\/span><\/a><\/li>\n<li id=\"menu-item-479\" class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item parent hfe-creative-menu\"><a href=\"https:\/\/www.cafeteriapuntoycoma.com\/en\/wp-json\/wp\/v2\/pages\/517\" class = \"hfe-menu-item\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/en_GB.png\" width=\"18\" height=\"12\" alt=\"en_GB\" title=\"English\"><\/span><\/a><\/li>\n<\/ul> \n\t\t\t\t<\/nav>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6dcdbd0 elementor-invisible\" data-id=\"6dcdbd0\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:600}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e33d619 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"e33d619\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Follow Us<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-beb4cc6 elementor-shape-circle elementor-grid-4 elementor-grid-mobile-4 e-grid-align-mobile-left e-grid-align-left e-grid-align-tablet-center elementor-widget elementor-widget-social-icons\" data-id=\"beb4cc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-animation-float elementor-repeater-item-71dd998\" href=\"https:\/\/www.facebook.com\/puntoycomavigo\/about?locale=es_ES\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-animation-float elementor-repeater-item-5f0ed35\" href=\"https:\/\/www.instagram.com\/puntoycomavigo\/?hl=es\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a1867e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a1867e1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4cc35a1\" data-id=\"4cc35a1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4b4e4b elementor-widget elementor-widget-text-editor\" data-id=\"b4b4e4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Copyright \u00a9 2024. All rights reserved.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8165c2f\" data-id=\"8165c2f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e38d0d elementor-widget elementor-widget-text-editor\" data-id=\"5e38d0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\"https:\/\/www.cafeteriapuntoycoma.com\/en\/politica-de-privacidad\/\">Pol\u00edtica de Privacidad<\/a><\/span>\u00a0 |\u00a0 <a href=\"https:\/\/www.cafeteriapuntoycoma.com\/en\/accesibilidad\/\"><span style=\"color: #ffffff;\">Accesibilidad<\/span><\/a>\u00a0 |\u00a0 <span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\"https:\/\/www.cafeteriapuntoycoma.com\/en\/politica-de-cookies\/\">Pol\u00edtica de Cookies<\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-1135679 e-flex e-con-boxed e-con e-parent\" data-id=\"1135679\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f03242f e-con-full e-flex e-con e-child\" data-id=\"f03242f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6bb4b11 elementor-widget elementor-widget-image\" data-id=\"6bb4b11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"235\" src=\"https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/ES-Financiado-por-la-Union-Europea_1.png\" class=\"attachment-large size-large wp-image-441\" alt=\"\" srcset=\"https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/ES-Financiado-por-la-Union-Europea_1.png 1024w, https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/ES-Financiado-por-la-Union-Europea_1-300x88.png 300w, https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/ES-Financiado-por-la-Union-Europea_1-768x226.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-59bbf18 e-con-full e-flex e-con e-child\" data-id=\"59bbf18\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ab2acf elementor-widget elementor-widget-image\" data-id=\"4ab2acf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"200\" src=\"https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/Logo-PRTR-1.png\" class=\"attachment-large size-large wp-image-440\" alt=\"\" srcset=\"https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/Logo-PRTR-1.png 1024w, https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/Logo-PRTR-1-300x75.png 300w, https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/Logo-PRTR-1-768x192.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>INICIO NOSOTROS MEN\u00da CONTACTO LL\u00c1MANOS Pol\u00edtica de Cookies POL\u00cdTICA DE COOKIES \u00a0 https:\/\/www.cafeteriapuntoycoma.com El acceso a este Sitio Web puede implicar la utilizaci\u00f3n de cookies. Las cookies son peque\u00f1as cantidades de informaci\u00f3n que se almacenan en el navegador utilizado por cada Usuario \u2014en los distintos dispositivos que pueda utilizar para navegar\u2014 para que el servidor [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-517","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de Cookies - Cafeter\u00eda Punto &amp; Coma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cafeteriapuntoycoma.com\/en\/politica-de-cookies\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de Cookies - Cafeter\u00eda Punto &amp; Coma\" \/>\n<meta property=\"og:description\" content=\"INICIO NOSOTROS MEN\u00da CONTACTO LL\u00c1MANOS Pol\u00edtica de Cookies POL\u00cdTICA DE COOKIES \u00a0 https:\/\/www.cafeteriapuntoycoma.com El acceso a este Sitio Web puede implicar la utilizaci\u00f3n de cookies. Las cookies son peque\u00f1as cantidades de informaci\u00f3n que se almacenan en el navegador utilizado por cada Usuario \u2014en los distintos dispositivos que pueda utilizar para navegar\u2014 para que el servidor [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cafeteriapuntoycoma.com\/en\/politica-de-cookies\/\" \/>\n<meta property=\"og:site_name\" content=\"Cafeter\u00eda Punto &amp; Coma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/puntoycomavigo\/about?locale=es_ES\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-13T11:54:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/Logo-pyc-02.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cafeteriapuntoycoma.com\\\/politica-de-cookies\\\/\",\"url\":\"https:\\\/\\\/www.cafeteriapuntoycoma.com\\\/politica-de-cookies\\\/\",\"name\":\"Pol\u00edtica de Cookies - Cafeter\u00eda Punto &amp; Coma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cafeteriapuntoycoma.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cafeteriapuntoycoma.com\\\/politica-de-cookies\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cafeteriapuntoycoma.com\\\/politica-de-cookies\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cafeteriapuntoycoma.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-pyc-02.png\",\"datePublished\":\"2024-06-13T11:28:23+00:00\",\"dateModified\":\"2024-06-13T11:54:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cafeteriapuntoycoma.com\\\/politica-de-cookies\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cafeteriapuntoycoma.com\\\/politica-de-cookies\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.cafeteriapuntoycoma.com\\\/politica-de-cookies\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cafeteriapuntoycoma.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-pyc-02.png\",\"contentUrl\":\"https:\\\/\\\/www.cafeteriapuntoycoma.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-pyc-02.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cafeteriapuntoycoma.com\\\/politica-de-cookies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.cafeteriapuntoycoma.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de Cookies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cafeteriapuntoycoma.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cafeteriapuntoycoma.com\\\/\",\"name\":\"Cafeter\u00eda Punto & Coma\",\"description\":\"Tu caf\u00e9-bar en Navia, Vigo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cafeteriapuntoycoma.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cafeteriapuntoycoma.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cafeteriapuntoycoma.com\\\/#organization\",\"name\":\"Cafeter\u00eda Punto & Coma\",\"url\":\"https:\\\/\\\/www.cafeteriapuntoycoma.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.cafeteriapuntoycoma.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cafeteriapuntoycoma.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-pyc-02.png\",\"contentUrl\":\"https:\\\/\\\/www.cafeteriapuntoycoma.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-pyc-02.png\",\"width\":700,\"height\":700,\"caption\":\"Cafeter\u00eda Punto & Coma\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cafeteriapuntoycoma.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/puntoycomavigo\\\/about?locale=es_ES\",\"https:\\\/\\\/www.instagram.com\\\/puntoycomavigo\\\/?hl=es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de Cookies - Cafeter\u00eda Punto &amp; Coma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cafeteriapuntoycoma.com\/en\/politica-de-cookies\/","og_locale":"en_GB","og_type":"article","og_title":"Pol\u00edtica de Cookies - Cafeter\u00eda Punto &amp; Coma","og_description":"INICIO NOSOTROS MEN\u00da CONTACTO LL\u00c1MANOS Pol\u00edtica de Cookies POL\u00cdTICA DE COOKIES \u00a0 https:\/\/www.cafeteriapuntoycoma.com El acceso a este Sitio Web puede implicar la utilizaci\u00f3n de cookies. Las cookies son peque\u00f1as cantidades de informaci\u00f3n que se almacenan en el navegador utilizado por cada Usuario \u2014en los distintos dispositivos que pueda utilizar para navegar\u2014 para que el servidor [&hellip;]","og_url":"https:\/\/www.cafeteriapuntoycoma.com\/en\/politica-de-cookies\/","og_site_name":"Cafeter\u00eda Punto &amp; Coma","article_publisher":"https:\/\/www.facebook.com\/puntoycomavigo\/about?locale=es_ES","article_modified_time":"2024-06-13T11:54:02+00:00","og_image":[{"url":"https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/Logo-pyc-02.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cafeteriapuntoycoma.com\/politica-de-cookies\/","url":"https:\/\/www.cafeteriapuntoycoma.com\/politica-de-cookies\/","name":"Pol\u00edtica de Cookies - Cafeter\u00eda Punto &amp; Coma","isPartOf":{"@id":"https:\/\/www.cafeteriapuntoycoma.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cafeteriapuntoycoma.com\/politica-de-cookies\/#primaryimage"},"image":{"@id":"https:\/\/www.cafeteriapuntoycoma.com\/politica-de-cookies\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/Logo-pyc-02.png","datePublished":"2024-06-13T11:28:23+00:00","dateModified":"2024-06-13T11:54:02+00:00","breadcrumb":{"@id":"https:\/\/www.cafeteriapuntoycoma.com\/politica-de-cookies\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cafeteriapuntoycoma.com\/politica-de-cookies\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.cafeteriapuntoycoma.com\/politica-de-cookies\/#primaryimage","url":"https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/Logo-pyc-02.png","contentUrl":"https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/Logo-pyc-02.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cafeteriapuntoycoma.com\/politica-de-cookies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.cafeteriapuntoycoma.com\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de Cookies"}]},{"@type":"WebSite","@id":"https:\/\/www.cafeteriapuntoycoma.com\/#website","url":"https:\/\/www.cafeteriapuntoycoma.com\/","name":"Punto &amp; Coma Caf\u00e9","description":"Tu caf\u00e9-bar en Navia, Vigo.","publisher":{"@id":"https:\/\/www.cafeteriapuntoycoma.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cafeteriapuntoycoma.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.cafeteriapuntoycoma.com\/#organization","name":"Punto &amp; Coma Caf\u00e9","url":"https:\/\/www.cafeteriapuntoycoma.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.cafeteriapuntoycoma.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/Logo-pyc-02.png","contentUrl":"https:\/\/www.cafeteriapuntoycoma.com\/wp-content\/uploads\/2024\/06\/Logo-pyc-02.png","width":700,"height":700,"caption":"Cafeter\u00eda Punto & Coma"},"image":{"@id":"https:\/\/www.cafeteriapuntoycoma.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/puntoycomavigo\/about?locale=es_ES","https:\/\/www.instagram.com\/puntoycomavigo\/?hl=es"]}]}},"_links":{"self":[{"href":"https:\/\/www.cafeteriapuntoycoma.com\/en\/wp-json\/wp\/v2\/pages\/517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cafeteriapuntoycoma.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cafeteriapuntoycoma.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cafeteriapuntoycoma.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cafeteriapuntoycoma.com\/en\/wp-json\/wp\/v2\/comments?post=517"}],"version-history":[{"count":10,"href":"https:\/\/www.cafeteriapuntoycoma.com\/en\/wp-json\/wp\/v2\/pages\/517\/revisions"}],"predecessor-version":[{"id":558,"href":"https:\/\/www.cafeteriapuntoycoma.com\/en\/wp-json\/wp\/v2\/pages\/517\/revisions\/558"}],"wp:attachment":[{"href":"https:\/\/www.cafeteriapuntoycoma.com\/en\/wp-json\/wp\/v2\/media?parent=517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}